{"id":9453,"date":"2026-06-09T00:00:00","date_gmt":"2026-06-08T22:00:00","guid":{"rendered":"https:\/\/domovista.de\/?post_type=immomakler_object&#038;p=9453"},"modified":"2026-06-09T13:14:04","modified_gmt":"2026-06-09T11:14:04","slug":"wohnung-dachgeschoss-in-goerlitz-mieten-911584-2","status":"publish","type":"immomakler_object","link":"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/","title":{"rendered":"Voll m\u00f6blierte 2-Raum-Dachgeschosswohnung in S\u00fcdstadtlage!"},"excerpt":{"rendered":"<p>2 Zimmer 90 m\u00b2 Dachgeschoss in G\u00f6rlitz zur Miete. Ausstattung: Einbauk\u00fcche, Fliesenboden, Laminatboden, etc.<\/p>\n","protected":false},"featured_media":9454,"template":"","meta":{"_angie_page":false},"immomakler_object_type":[43,42],"immomakler_object_country":[32],"immomakler_object_vermarktung":[30],"immomakler_object_nutzungsart":[31],"immomakler_object_location":[33],"immomakler_object_feature":[38,39,34,36,112,37,109],"immomakler_object_status":[41],"class_list":["post-9453","immomakler_object","type-immomakler_object","status-publish","has-post-thumbnail","hentry","immomakler_object_type-dachgeschoss","immomakler_object_type-wohnung","immomakler_object_country-deutschland","immomakler_object_vermarktung-miete","immomakler_object_nutzungsart-wohnen","immomakler_object_location-goerlitz","immomakler_object_feature-badewanne","immomakler_object_feature-denkmalgeschuetzt","immomakler_object_feature-einbaukueche","immomakler_object_feature-fliesenboden","immomakler_object_feature-gaeste-wc","immomakler_object_feature-laminatboden","immomakler_object_feature-tageslichtbad","immomakler_object_status-offen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dachgeschoss in G\u00f6rlitz, 90 m\u00b2 - DOMOVISTA<\/title>\n<meta name=\"description\" content=\"&quot;Voll m\u00f6blierte 2-Raum-Dachgeschosswohnung in S\u00fcdstadtlage!&quot; - 2 Zimmer 90 m\u00b2 Dachgeschoss in G\u00f6rlitz zur Miete. Ausstattung: Einbauk\u00fcche, Fliesenboden, Laminatboden, etc.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dachgeschoss in G\u00f6rlitz, 90 m\u00b2 - DOMOVISTA\" \/>\n<meta property=\"og:description\" content=\"&quot;Voll m\u00f6blierte 2-Raum-Dachgeschosswohnung in S\u00fcdstadtlage!&quot; - 2 Zimmer 90 m\u00b2 Dachgeschoss in G\u00f6rlitz zur Miete. Ausstattung: Einbauk\u00fcche, Fliesenboden, Laminatboden, etc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/\" \/>\n<meta property=\"og:site_name\" content=\"DOMOVISTA\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-09T11:14:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/domovista.de\/wp-content\/uploads\/immomakler\/attachments\/5795a09563f6465301796e2c2b78517d\/28e13703-982c419335745c068d8396766ace1c2f.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/immobilien\\\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\\\/\",\"url\":\"https:\\\/\\\/domovista.de\\\/en\\\/immobilien\\\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\\\/\",\"name\":\"Dachgeschoss in G\u00f6rlitz, 90 m\u00b2 - DOMOVISTA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/immobilien\\\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/immobilien\\\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/domovista.de\\\/wp-content\\\/uploads\\\/immomakler\\\/attachments\\\/5795a09563f6465301796e2c2b78517d\\\/28e13703-982c419335745c068d8396766ace1c2f.jpg\",\"datePublished\":\"2026-06-08T22:00:00+00:00\",\"dateModified\":\"2026-06-09T11:14:04+00:00\",\"description\":\"\\\"Voll m\u00f6blierte 2-Raum-Dachgeschosswohnung in S\u00fcdstadtlage!\\\" - 2 Zimmer 90 m\u00b2 Dachgeschoss in G\u00f6rlitz zur Miete. Ausstattung: Einbauk\u00fcche, Fliesenboden, Laminatboden, etc.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/immobilien\\\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/domovista.de\\\/en\\\/immobilien\\\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/immobilien\\\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/domovista.de\\\/wp-content\\\/uploads\\\/immomakler\\\/attachments\\\/5795a09563f6465301796e2c2b78517d\\\/28e13703-982c419335745c068d8396766ace1c2f.jpg\",\"contentUrl\":\"https:\\\/\\\/domovista.de\\\/wp-content\\\/uploads\\\/immomakler\\\/attachments\\\/5795a09563f6465301796e2c2b78517d\\\/28e13703-982c419335745c068d8396766ace1c2f.jpg\",\"width\":2048,\"height\":1536,\"caption\":\"Wohnzimmer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/immobilien\\\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/domovista.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Properties\",\"item\":\"https:\\\/\\\/domovista.de\\\/en\\\/immobilien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"G\u00f6rlitz\",\"item\":\"https:\\\/\\\/domovista.de\\\/en\\\/immobilien-ort\\\/goerlitz\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Voll m\u00f6blierte 2-Raum-Dachgeschosswohnung in S\u00fcdstadtlage!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/domovista.de\\\/en\\\/\",\"name\":\"DOMOVISTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/domovista.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/#organization\",\"name\":\"DOMOVISTA\",\"url\":\"https:\\\/\\\/domovista.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/domovista.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/domovista-hq-sitelogo.png\",\"contentUrl\":\"https:\\\/\\\/domovista.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/domovista-hq-sitelogo.png\",\"width\":1000,\"height\":250,\"caption\":\"DOMOVISTA\"},\"image\":{\"@id\":\"https:\\\/\\\/domovista.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/domovista_immobilien\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dachgeschoss in G\u00f6rlitz, 90 m\u00b2 - DOMOVISTA","description":"\"Voll m\u00f6blierte 2-Raum-Dachgeschosswohnung in S\u00fcdstadtlage!\" - 2 Zimmer 90 m\u00b2 Dachgeschoss in G\u00f6rlitz zur Miete. Ausstattung: Einbauk\u00fcche, Fliesenboden, Laminatboden, etc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/","og_locale":"en_US","og_type":"article","og_title":"Dachgeschoss in G\u00f6rlitz, 90 m\u00b2 - DOMOVISTA","og_description":"\"Voll m\u00f6blierte 2-Raum-Dachgeschosswohnung in S\u00fcdstadtlage!\" - 2 Zimmer 90 m\u00b2 Dachgeschoss in G\u00f6rlitz zur Miete. Ausstattung: Einbauk\u00fcche, Fliesenboden, Laminatboden, etc.","og_url":"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/","og_site_name":"DOMOVISTA","article_modified_time":"2026-06-09T11:14:04+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/domovista.de\/wp-content\/uploads\/immomakler\/attachments\/5795a09563f6465301796e2c2b78517d\/28e13703-982c419335745c068d8396766ace1c2f.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/","url":"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/","name":"Dachgeschoss in G\u00f6rlitz, 90 m\u00b2 - DOMOVISTA","isPartOf":{"@id":"https:\/\/domovista.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/#primaryimage"},"image":{"@id":"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/#primaryimage"},"thumbnailUrl":"https:\/\/domovista.de\/wp-content\/uploads\/immomakler\/attachments\/5795a09563f6465301796e2c2b78517d\/28e13703-982c419335745c068d8396766ace1c2f.jpg","datePublished":"2026-06-08T22:00:00+00:00","dateModified":"2026-06-09T11:14:04+00:00","description":"\"Voll m\u00f6blierte 2-Raum-Dachgeschosswohnung in S\u00fcdstadtlage!\" - 2 Zimmer 90 m\u00b2 Dachgeschoss in G\u00f6rlitz zur Miete. Ausstattung: Einbauk\u00fcche, Fliesenboden, Laminatboden, etc.","breadcrumb":{"@id":"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/#primaryimage","url":"https:\/\/domovista.de\/wp-content\/uploads\/immomakler\/attachments\/5795a09563f6465301796e2c2b78517d\/28e13703-982c419335745c068d8396766ace1c2f.jpg","contentUrl":"https:\/\/domovista.de\/wp-content\/uploads\/immomakler\/attachments\/5795a09563f6465301796e2c2b78517d\/28e13703-982c419335745c068d8396766ace1c2f.jpg","width":2048,"height":1536,"caption":"Wohnzimmer"},{"@type":"BreadcrumbList","@id":"https:\/\/domovista.de\/en\/immobilien\/wohnung-dachgeschoss-in-goerlitz-mieten-911584-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/domovista.de\/en\/"},{"@type":"ListItem","position":2,"name":"Properties","item":"https:\/\/domovista.de\/en\/immobilien\/"},{"@type":"ListItem","position":3,"name":"G\u00f6rlitz","item":"https:\/\/domovista.de\/en\/immobilien-ort\/goerlitz\/"},{"@type":"ListItem","position":4,"name":"Voll m\u00f6blierte 2-Raum-Dachgeschosswohnung in S\u00fcdstadtlage!"}]},{"@type":"WebSite","@id":"https:\/\/domovista.de\/en\/#website","url":"https:\/\/domovista.de\/en\/","name":"DOMOVISTA","description":"","publisher":{"@id":"https:\/\/domovista.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/domovista.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/domovista.de\/en\/#organization","name":"DOMOVISTA","url":"https:\/\/domovista.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/domovista.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/domovista.de\/wp-content\/uploads\/2026\/05\/domovista-hq-sitelogo.png","contentUrl":"https:\/\/domovista.de\/wp-content\/uploads\/2026\/05\/domovista-hq-sitelogo.png","width":1000,"height":250,"caption":"DOMOVISTA"},"image":{"@id":"https:\/\/domovista.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/domovista_immobilien\/"]}]}},"_links":{"self":[{"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/immomakler_object\/9453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/immomakler_object"}],"about":[{"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/types\/immomakler_object"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/media\/9454"}],"wp:attachment":[{"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/media?parent=9453"}],"wp:term":[{"taxonomy":"immomakler_object_type","embeddable":true,"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/immomakler_object_type?post=9453"},{"taxonomy":"immomakler_object_country","embeddable":true,"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/immomakler_object_country?post=9453"},{"taxonomy":"immomakler_object_vermarktung","embeddable":true,"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/immomakler_object_vermarktung?post=9453"},{"taxonomy":"immomakler_object_nutzungsart","embeddable":true,"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/immomakler_object_nutzungsart?post=9453"},{"taxonomy":"immomakler_object_location","embeddable":true,"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/immomakler_object_location?post=9453"},{"taxonomy":"immomakler_object_feature","embeddable":true,"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/immomakler_object_feature?post=9453"},{"taxonomy":"immomakler_object_status","embeddable":true,"href":"https:\/\/domovista.de\/en\/wp-json\/wp\/v2\/immomakler_object_status?post=9453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}